{"id":1051,"date":"2024-05-28T17:51:27","date_gmt":"2024-05-28T15:51:27","guid":{"rendered":"https:\/\/www.abk-stuttgart.de\/person\/christian-degenhardt-2\/"},"modified":"2024-09-17T14:24:35","modified_gmt":"2024-09-17T12:24:35","slug":"christian-degenhardt-2","status":"publish","type":"person","link":"https:\/\/www.abk-stuttgart.de\/en\/person\/christian-degenhardt-2\/","title":{"rendered":"Dipl.-Ing. Christian Degenhardt"},"content":{"rendered":"\n<details class=\"block-bundle collapse-section\">\n    <summary class=\"block block-subsection-title\">\n        <h3>Brief Vita<\/h3>    <\/summary>\n    \n\n    <div class=\"block block-text\">\n        <div class=\"fs-text\">\n            \n<p class=\"vita\"><span class=\"year\">seit 2014<\/span><span class=\"text\">\nAkademischer Mitarbeiter in der Klasse&nbsp;f&uuml;r Geb&auml;udetechnologie und klimagerechtes Entwerfen in der Fachgruppe Architektur an der&nbsp;Staatlichen Akademie der Bildenden K&uuml;nste Stuttgart<\/span><\/p>\n<p>Christian Degenhardt studierte Architektur an der RWTH Aachen und erwarb sein Diplom im Bereich &bdquo;Technischer Ausbau und Entwerfen&ldquo; mit dem Fokus auf nachhaltiger Bestandsentwicklung. Unmittelbar nach dem Studium erfolgte der Einstieg in die angewandte Architektur bei Holzh&uuml;ter Architektur und Holzbau GmbH in Aachen. Dabei stand die &Uuml;bersetzung von der Planungsphase zur Ausf&uuml;hrungsphase im Vordergrund. Mit der Orientierung zur&uuml;ck in die schw&auml;bische Heimat, war es m&ouml;glich ein Praktikum bei der Firma &bdquo;Transsolar KlimaEngineering&ldquo;&nbsp;Stuttgart zu absolvieren, welches in eine Anstellung und freie Mitarbeit m&uuml;ndete. Dies er&ouml;ffnete die M&ouml;glichkeit dem bereits im Studium selbst gew&auml;hlten Schwerpunkt des energieeffizienten und klimagerechten Bauens zu vertiefen. Die Arbeitsfelder bei Transsolar lagen zum einen in der Assistenz bei der Projektarbeit und Wettbewerbsbearbeitung von Energie- und Komfortkonzepten. Zum anderen betreute er die <em>open-source<\/em>-Initiative &bdquo;Future City Lab&ldquo;. Zudem nahm er sich von 2013 bis 2015 als Hauptverantwortlicher der Entwicklung des Programms sowie der Umsetzung und Leitung der Transsolar Academy&nbsp;an. Nach erfolgreicher Integration des Fellowship-Programms der Transsolar Academy&nbsp;in die Unternehmensstruktur ist er seit Sommer 2015 unterst&uuml;tzend in reduzierter Rolle als freier Mitarbeiter t&auml;tig. Des Weiteren f&uuml;hrt er seit 2014 seine freiberufliche T&auml;tigkeit bei Jan-Andr&eacute; Meyer Architekten in K&ouml;ln mit dem Schwerpunkt im architektonischen Entwurf fort.<\/p>\n\n        <\/div>\n    <\/div>\n\n\n<\/details>\n","protected":false},"author":6,"featured_media":0,"template":"","meta":{"_acf_changed":true},"faculty":[11],"function":[],"committee":[],"location":[63],"position":[],"class_list":["post-1051","person","type-person","status-publish","hentry","faculty-architektur","location-campus-weissenhof-neubau-1"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.abk-stuttgart.de\/en\/wp-json\/wp\/v2\/person\/1051","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.abk-stuttgart.de\/en\/wp-json\/wp\/v2\/person"}],"about":[{"href":"https:\/\/www.abk-stuttgart.de\/en\/wp-json\/wp\/v2\/types\/person"}],"author":[{"embeddable":true,"href":"https:\/\/www.abk-stuttgart.de\/en\/wp-json\/wp\/v2\/users\/6"}],"wp:attachment":[{"href":"https:\/\/www.abk-stuttgart.de\/en\/wp-json\/wp\/v2\/media?parent=1051"}],"wp:term":[{"taxonomy":"faculty","embeddable":true,"href":"https:\/\/www.abk-stuttgart.de\/en\/wp-json\/wp\/v2\/faculty?post=1051"},{"taxonomy":"function","embeddable":true,"href":"https:\/\/www.abk-stuttgart.de\/en\/wp-json\/wp\/v2\/function?post=1051"},{"taxonomy":"committee","embeddable":true,"href":"https:\/\/www.abk-stuttgart.de\/en\/wp-json\/wp\/v2\/committee?post=1051"},{"taxonomy":"location","embeddable":true,"href":"https:\/\/www.abk-stuttgart.de\/en\/wp-json\/wp\/v2\/location?post=1051"},{"taxonomy":"position","embeddable":true,"href":"https:\/\/www.abk-stuttgart.de\/en\/wp-json\/wp\/v2\/position?post=1051"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}